{"id":961,"date":"2021-12-10T16:09:35","date_gmt":"2021-12-10T15:09:35","guid":{"rendered":"https:\/\/lenuslab.com\/castellabateapartments\/?p=961"},"modified":"2021-12-10T17:02:50","modified_gmt":"2021-12-10T16:02:50","slug":"ottima-posizione","status":"publish","type":"post","link":"https:\/\/castellabateapartments.it\/it\/2021\/12\/10\/ottima-posizione\/","title":{"rendered":"Ottima posizione"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]<\/p>\n<p style=\"text-align: center;\">Ho soggiornato in uno degli appartamenti di Castellabate Apartments lo scorso luglio. Sono stato veramente bene, ospitalit\u00e0 e soprattutto posizione invidiabile.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><strong>[Marco Tartaglia]<\/strong><\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"[vc_row][vc_column][vc_column_text] Ho soggiornato in uno degli appartamenti di Castellabate Apartments lo scorso luglio. Sono stato veramente bene, ospitalit\u00e0 e soprattutto posizione invidiabile. &nbsp; [Marco Tartaglia] [\/vc_column_text][\/vc_column][\/vc_row]","protected":false},"author":14,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[1,13],"tags":[],"class_list":["post-961","post","type-post","status-publish","format-standard","hentry","category-non-categorizzato","category-recensioni"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ottima posizione - Castellabate apartments<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/castellabateapartments.it\/it\/2021\/12\/10\/ottima-posizione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ottima posizione - Castellabate apartments\" \/>\n<meta property=\"og:description\" content=\"[vc_row][vc_column][vc_column_text] Ho soggiornato in uno degli appartamenti di Castellabate Apartments lo scorso luglio. Sono stato veramente bene, ospitalit\u00e0 e soprattutto posizione invidiabile. &nbsp; [Marco Tartaglia] [\/vc_column_text][\/vc_column][\/vc_row]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/castellabateapartments.it\/it\/2021\/12\/10\/ottima-posizione\/\" \/>\n<meta property=\"og:site_name\" content=\"Castellabate apartments\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-10T15:09:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-10T16:02:50+00:00\" \/>\n<meta name=\"author\" content=\"Annalisa Milione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Annalisa Milione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/castellabateapartments.it\\\/it\\\/2021\\\/12\\\/10\\\/ottima-posizione\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/castellabateapartments.it\\\/it\\\/2021\\\/12\\\/10\\\/ottima-posizione\\\/\"},\"author\":{\"name\":\"Annalisa Milione\",\"@id\":\"https:\\\/\\\/castellabateapartments.it\\\/it\\\/#\\\/schema\\\/person\\\/3dcdc98aa7994b6d15aa1da7e758a408\"},\"headline\":\"Ottima posizione\",\"datePublished\":\"2021-12-10T15:09:35+00:00\",\"dateModified\":\"2021-12-10T16:02:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/castellabateapartments.it\\\/it\\\/2021\\\/12\\\/10\\\/ottima-posizione\\\/\"},\"wordCount\":40,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/castellabateapartments.it\\\/it\\\/#organization\"},\"articleSection\":[\"Non categorizzato\",\"Recensioni\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/castellabateapartments.it\\\/it\\\/2021\\\/12\\\/10\\\/ottima-posizione\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/castellabateapartments.it\\\/it\\\/2021\\\/12\\\/10\\\/ottima-posizione\\\/\",\"url\":\"https:\\\/\\\/castellabateapartments.it\\\/it\\\/2021\\\/12\\\/10\\\/ottima-posizione\\\/\",\"name\":\"Ottima posizione - Castellabate apartments\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/castellabateapartments.it\\\/it\\\/#website\"},\"datePublished\":\"2021-12-10T15:09:35+00:00\",\"dateModified\":\"2021-12-10T16:02:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/castellabateapartments.it\\\/it\\\/2021\\\/12\\\/10\\\/ottima-posizione\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/castellabateapartments.it\\\/it\\\/2021\\\/12\\\/10\\\/ottima-posizione\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/castellabateapartments.it\\\/it\\\/2021\\\/12\\\/10\\\/ottima-posizione\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/castellabateapartments.it\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ottima posizione\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/castellabateapartments.it\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/castellabateapartments.it\\\/it\\\/\",\"name\":\"Castellabate apartments\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/castellabateapartments.it\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/castellabateapartments.it\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/castellabateapartments.it\\\/it\\\/#organization\",\"name\":\"Castellabate apartments\",\"url\":\"https:\\\/\\\/castellabateapartments.it\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/castellabateapartments.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/castellabateapartments.it\\\/wp-content\\\/uploads\\\/sites\\\/18\\\/2021\\\/10\\\/cropped-01.png\",\"contentUrl\":\"https:\\\/\\\/castellabateapartments.it\\\/wp-content\\\/uploads\\\/sites\\\/18\\\/2021\\\/10\\\/cropped-01.png\",\"width\":2041,\"height\":568,\"caption\":\"Castellabate apartments\"},\"image\":{\"@id\":\"https:\\\/\\\/castellabateapartments.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/castellabateapartments.it\\\/it\\\/#\\\/schema\\\/person\\\/3dcdc98aa7994b6d15aa1da7e758a408\",\"name\":\"Annalisa Milione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/35507d816d8aad3c8a6519ffb64b8bfb205c59fb52f7eecf549f370b3a9de496?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/35507d816d8aad3c8a6519ffb64b8bfb205c59fb52f7eecf549f370b3a9de496?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/35507d816d8aad3c8a6519ffb64b8bfb205c59fb52f7eecf549f370b3a9de496?s=96&d=mm&r=g\",\"caption\":\"Annalisa Milione\"},\"url\":\"https:\\\/\\\/castellabateapartments.it\\\/it\\\/author\\\/annalisamilione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ottima posizione - Castellabate apartments","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/castellabateapartments.it\/it\/2021\/12\/10\/ottima-posizione\/","og_locale":"it_IT","og_type":"article","og_title":"Ottima posizione - Castellabate apartments","og_description":"[vc_row][vc_column][vc_column_text] Ho soggiornato in uno degli appartamenti di Castellabate Apartments lo scorso luglio. Sono stato veramente bene, ospitalit\u00e0 e soprattutto posizione invidiabile. &nbsp; [Marco Tartaglia] [\/vc_column_text][\/vc_column][\/vc_row]","og_url":"https:\/\/castellabateapartments.it\/it\/2021\/12\/10\/ottima-posizione\/","og_site_name":"Castellabate apartments","article_published_time":"2021-12-10T15:09:35+00:00","article_modified_time":"2021-12-10T16:02:50+00:00","author":"Annalisa Milione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Annalisa Milione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/castellabateapartments.it\/it\/2021\/12\/10\/ottima-posizione\/#article","isPartOf":{"@id":"https:\/\/castellabateapartments.it\/it\/2021\/12\/10\/ottima-posizione\/"},"author":{"name":"Annalisa Milione","@id":"https:\/\/castellabateapartments.it\/it\/#\/schema\/person\/3dcdc98aa7994b6d15aa1da7e758a408"},"headline":"Ottima posizione","datePublished":"2021-12-10T15:09:35+00:00","dateModified":"2021-12-10T16:02:50+00:00","mainEntityOfPage":{"@id":"https:\/\/castellabateapartments.it\/it\/2021\/12\/10\/ottima-posizione\/"},"wordCount":40,"commentCount":0,"publisher":{"@id":"https:\/\/castellabateapartments.it\/it\/#organization"},"articleSection":["Non categorizzato","Recensioni"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/castellabateapartments.it\/it\/2021\/12\/10\/ottima-posizione\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/castellabateapartments.it\/it\/2021\/12\/10\/ottima-posizione\/","url":"https:\/\/castellabateapartments.it\/it\/2021\/12\/10\/ottima-posizione\/","name":"Ottima posizione - Castellabate apartments","isPartOf":{"@id":"https:\/\/castellabateapartments.it\/it\/#website"},"datePublished":"2021-12-10T15:09:35+00:00","dateModified":"2021-12-10T16:02:50+00:00","breadcrumb":{"@id":"https:\/\/castellabateapartments.it\/it\/2021\/12\/10\/ottima-posizione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/castellabateapartments.it\/it\/2021\/12\/10\/ottima-posizione\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/castellabateapartments.it\/it\/2021\/12\/10\/ottima-posizione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/castellabateapartments.it\/it\/"},{"@type":"ListItem","position":2,"name":"Ottima posizione"}]},{"@type":"WebSite","@id":"https:\/\/castellabateapartments.it\/it\/#website","url":"https:\/\/castellabateapartments.it\/it\/","name":"Castellabate apartments","description":"","publisher":{"@id":"https:\/\/castellabateapartments.it\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/castellabateapartments.it\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/castellabateapartments.it\/it\/#organization","name":"Castellabate apartments","url":"https:\/\/castellabateapartments.it\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/castellabateapartments.it\/it\/#\/schema\/logo\/image\/","url":"https:\/\/castellabateapartments.it\/wp-content\/uploads\/sites\/18\/2021\/10\/cropped-01.png","contentUrl":"https:\/\/castellabateapartments.it\/wp-content\/uploads\/sites\/18\/2021\/10\/cropped-01.png","width":2041,"height":568,"caption":"Castellabate apartments"},"image":{"@id":"https:\/\/castellabateapartments.it\/it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/castellabateapartments.it\/it\/#\/schema\/person\/3dcdc98aa7994b6d15aa1da7e758a408","name":"Annalisa Milione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/35507d816d8aad3c8a6519ffb64b8bfb205c59fb52f7eecf549f370b3a9de496?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/35507d816d8aad3c8a6519ffb64b8bfb205c59fb52f7eecf549f370b3a9de496?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/35507d816d8aad3c8a6519ffb64b8bfb205c59fb52f7eecf549f370b3a9de496?s=96&d=mm&r=g","caption":"Annalisa Milione"},"url":"https:\/\/castellabateapartments.it\/it\/author\/annalisamilione\/"}]}},"_links":{"self":[{"href":"https:\/\/castellabateapartments.it\/it\/wp-json\/wp\/v2\/posts\/961","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/castellabateapartments.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/castellabateapartments.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/castellabateapartments.it\/it\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/castellabateapartments.it\/it\/wp-json\/wp\/v2\/comments?post=961"}],"version-history":[{"count":3,"href":"https:\/\/castellabateapartments.it\/it\/wp-json\/wp\/v2\/posts\/961\/revisions"}],"predecessor-version":[{"id":970,"href":"https:\/\/castellabateapartments.it\/it\/wp-json\/wp\/v2\/posts\/961\/revisions\/970"}],"wp:attachment":[{"href":"https:\/\/castellabateapartments.it\/it\/wp-json\/wp\/v2\/media?parent=961"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/castellabateapartments.it\/it\/wp-json\/wp\/v2\/categories?post=961"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/castellabateapartments.it\/it\/wp-json\/wp\/v2\/tags?post=961"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}